{"id":1062,"date":"2017-11-03T10:54:52","date_gmt":"2017-11-03T09:54:52","guid":{"rendered":"https:\/\/www.eye-track-sport.com\/nl\/?page_id=1062"},"modified":"2024-07-10T11:54:33","modified_gmt":"2024-07-10T09:54:33","slug":"welcome","status":"publish","type":"page","link":"https:\/\/eye-track-sport.com\/nl\/","title":{"rendered":"Welcome"},"content":{"rendered":"<div id='full_slider_1'  class='avia-fullwidth-slider main_color avia-shadow   avia-builder-el-0  el_before_av_layout_row  avia-builder-el-first   container_wrap sidebar_right'  ><div  class='avia-slideshow av-lyfnxlgc-51c9086d28c44483e78a7b412318f631 avia-slideshow-featured_large av_slideshow_full avia-fade-slider av-slideshow-ui av-control-minimal av-slideshow-manual av-loop-once av-loop-manual-endless av-default-height-applied   avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;fade&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:6,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 42%;'><li  class='avia-slideshow-slide av-lyfnxlgc-51c9086d28c44483e78a7b412318f631__0  slide-1 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-4197 avia-img-lazy-loading-not-4197\"  src=\"https:\/\/eye-track-sport.com\/wp-content\/uploads\/2024\/07\/fianco-1500x630.jpg\" width=\"1500\" height=\"630\" title='fianco' alt=''  itemprop=\"thumbnailUrl\"   \/><\/div><\/li><li  class='avia-slideshow-slide av-lyfnxlgc-51c9086d28c44483e78a7b412318f631__1  slide-2 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-4203 avia-img-lazy-loading-not-4203\"  src=\"https:\/\/eye-track-sport.com\/wp-content\/uploads\/2024\/07\/20i6371_bright-1500x630.jpg\" width=\"1500\" height=\"630\" title='20i6371_bright' alt=''  itemprop=\"thumbnailUrl\"   \/><\/div><\/li><li  class='avia-slideshow-slide av-lyfnxlgc-51c9086d28c44483e78a7b412318f631__2  slide-3 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-3178 avia-img-lazy-loading-not-3178\"  src=\"https:\/\/eye-track-sport.com\/wp-content\/uploads\/2021\/08\/winter-1500x630.jpg\" width=\"1500\" height=\"630\" title='winter' alt=''  itemprop=\"thumbnailUrl\"   \/><\/div><\/li><li  class='avia-slideshow-slide av-lyfnxlgc-51c9086d28c44483e78a7b412318f631__3  slide-4 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-3208 avia-img-lazy-loading-not-3208\"  src=\"https:\/\/eye-track-sport.com\/wp-content\/uploads\/2021\/09\/applicazioni_civili_meter_detector_resized-1500x630.png\" width=\"1500\" height=\"630\" title='applicazioni_civili_meter_detector_resized' alt=''  itemprop=\"thumbnailUrl\"   \/><\/div><\/li><\/ul><div class='avia-slideshow-arrows avia-slideshow-controls' ><a href='#prev' class='prev-slide ' aria-hidden='true' data-av_icon='\ue87c' data-av_iconfont='entypo-fontello'  tabindex='-1'>Vorige<\/a><a href='#next' class='next-slide ' aria-hidden='true' data-av_icon='\ue87d' data-av_iconfont='entypo-fontello'  tabindex='-1'>Volgende<\/a><\/div><div class='avia-slideshow-dots avia-slideshow-controls'><a href='#1' class='goto-slide active' >1<\/a><a href='#2' class='goto-slide ' >2<\/a><a href='#3' class='goto-slide ' >3<\/a><a href='#4' class='goto-slide ' >4<\/a><\/div><\/div><\/div>\n<div id='av-layout-grid-1'  class='av-layout-grid-container av-av_layout_row-caf1f26e08707a2ebe9176b630e736c2 entry-content-wrapper main_color av-flex-cells  avia-builder-el-1  el_after_av_slideshow_full  el_before_av_section  grid-row-not-first  container_wrap sidebar_right'  >\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_cell_one_third-44a25fd51752c3990609fc678dc676e0\">\n.flex_cell.av-av_cell_one_third-44a25fd51752c3990609fc678dc676e0{\nvertical-align:top;\nbackground-color:#150959;\n}\n.responsive #top #wrap_all .flex_cell.av-av_cell_one_third-44a25fd51752c3990609fc678dc676e0{\npadding:90px 50px 90px 50px !important;\n}\n<\/style>\n<div class='flex_cell av-av_cell_one_third-44a25fd51752c3990609fc678dc676e0 av-gridrow-cell av_one_third no_margin  avia-builder-el-2  el_before_av_cell_one_third  avia-builder-el-first  avia-full-stretch'  ><div class='flex_cell_inner'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_icon_box-5ea7ee97a148e29a6e20f4398e90b489\">\n.iconbox.av-av_icon_box-5ea7ee97a148e29a6e20f4398e90b489 .iconbox_icon{\nborder:1px solid #ffffff;\ncolor:#ffffff;\n}\n#top #wrap_all .iconbox.av-av_icon_box-5ea7ee97a148e29a6e20f4398e90b489 .iconbox_content_title{\ncolor:#ffffff;\n}\n.iconbox.av-av_icon_box-5ea7ee97a148e29a6e20f4398e90b489 .iconbox_content_container{\ncolor:#ffffff;\n}\n<\/style>\n<article  class='iconbox iconbox_left_content av-av_icon_box-5ea7ee97a148e29a6e20f4398e90b489  avia-builder-el-3  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_icon heading-color\" aria-hidden='true' data-av_icon='\ue826' data-av_iconfont='entypo-fontello'><\/div><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icoon: CONTROLEER JOUW MOTOCROSSBAAN\"><h3 class='iconbox_content_title '  itemprop=\"headline\" >CONTROLEER JOUW MOTOCROSSBAAN<\/h3><\/header><div class='iconbox_content_container av_inherit_color'  itemprop=\"text\" ><p>Een onzichtbaar <strong>elektronisch veiligheidssysteem<\/strong> controleert motorcrossbanen, net als een track marshal en informeert rijders van een gevaarlijke situatie.<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article>\n<\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_cell_one_third-ad7442251f098cebf5d41199d5c61d4c\">\n.flex_cell.av-av_cell_one_third-ad7442251f098cebf5d41199d5c61d4c{\nvertical-align:top;\nbackground-color:#f7cd46;\n}\n.responsive #top #wrap_all .flex_cell.av-av_cell_one_third-ad7442251f098cebf5d41199d5c61d4c{\npadding:90px 50px 90px 50px !important;\n}\n<\/style>\n<div class='flex_cell av-av_cell_one_third-ad7442251f098cebf5d41199d5c61d4c av-gridrow-cell av_one_third no_margin  avia-builder-el-4  el_after_av_cell_one_third  el_before_av_cell_one_third  avia-full-stretch'  ><div class='flex_cell_inner'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_icon_box-a9d2eaf82356b868ed614c48c8c506be\">\n.iconbox.av-av_icon_box-a9d2eaf82356b868ed614c48c8c506be .iconbox_icon{\ncolor:#ffffff;\n}\n#top #wrap_all .iconbox.av-av_icon_box-a9d2eaf82356b868ed614c48c8c506be .iconbox_content_title{\ncolor:#ffffff;\n}\n.iconbox.av-av_icon_box-a9d2eaf82356b868ed614c48c8c506be .iconbox_content_container{\ncolor:#ffffff;\n}\n<\/style>\n<article  class='iconbox iconbox_left_content av-av_icon_box-a9d2eaf82356b868ed614c48c8c506be  avia-builder-el-5  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_icon heading-color\" aria-hidden='true' data-av_icon='\ue860' data-av_iconfont='entypo-fontello'><\/div><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icoon: HET KAN OVERAL WORDEN GEINSTALEERD\"><h3 class='iconbox_content_title '  itemprop=\"headline\" >HET KAN OVERAL WORDEN GEINSTALEERD<\/h3><\/header><div class='iconbox_content_container av_inherit_color'  itemprop=\"text\" ><p>EYE-TRACK kan op alle banen worden ge\u00efnstalleerd en kan alle rijders controleren.<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article>\n<\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_cell_one_third-44a25fd51752c3990609fc678dc676e0\">\n.flex_cell.av-av_cell_one_third-44a25fd51752c3990609fc678dc676e0{\nvertical-align:top;\nbackground-color:#150959;\n}\n.responsive #top #wrap_all .flex_cell.av-av_cell_one_third-44a25fd51752c3990609fc678dc676e0{\npadding:90px 50px 90px 50px !important;\n}\n<\/style>\n<div class='flex_cell av-av_cell_one_third-44a25fd51752c3990609fc678dc676e0 av-gridrow-cell av_one_third no_margin  avia-builder-el-6  el_after_av_cell_one_third  avia-builder-el-last  avia-full-stretch'  ><div class='flex_cell_inner'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_icon_box-faff66d249fc538c7297639a81870de8\">\n.iconbox.av-av_icon_box-faff66d249fc538c7297639a81870de8 .iconbox_icon{\ncolor:#ffffff;\n}\n#top #wrap_all .iconbox.av-av_icon_box-faff66d249fc538c7297639a81870de8 .iconbox_content_title{\ncolor:#ffffff;\n}\n.iconbox.av-av_icon_box-faff66d249fc538c7297639a81870de8 .iconbox_content_container{\ncolor:#ffffff;\n}\n<\/style>\n<article  class='iconbox iconbox_left_content av-av_icon_box-faff66d249fc538c7297639a81870de8  avia-builder-el-7  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_icon heading-color\" aria-hidden='true' data-av_icon='\ue82a' data-av_iconfont='entypo-fontello'><\/div><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icoon: VERPLICHT OP DE BAAN\"><h3 class='iconbox_content_title '  itemprop=\"headline\" >VERPLICHT OP DE BAAN<\/h3><\/header><div class='iconbox_content_container av_inherit_color'  itemprop=\"text\" ><p style=\"text-align: left;\"><strong>Onder FMI<\/strong> (&#8216;Federazione Motociclistica Italiana&#8217;) regelgeving moet de aanwezigheid van een track marshal of een elektronisch bewakingssysteem worden gewaarborgd tijdens de trainingen.<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article>\n<\/div><\/div>\n<\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lyfnyd06-e623b5d3312d8eafa10917557c242d06\">\n.avia-section.av-lyfnyd06-e623b5d3312d8eafa10917557c242d06{\nbackground-repeat:no-repeat;\nbackground-image:url(https:\/\/eye-track-sport.com\/wp-content\/uploads\/2024\/07\/083_EyeTrack_Roma_05_2019.jpg);\nbackground-position:50% 50%;\nbackground-attachment:fixed;\n}\n.avia-section.av-lyfnyd06-e623b5d3312d8eafa10917557c242d06 .av-section-color-overlay{\nopacity:0.7;\nbackground-color:#000000;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-lyfnyd06-e623b5d3312d8eafa10917557c242d06 alternate_color avia-section-huge avia-no-border-styling  avia-builder-el-8  el_after_av_layout_row  el_before_av_section  avia-full-stretch avia-bg-style-fixed av-section-color-overlay-active container_wrap sidebar_right'  data-section-bg-repeat='stretch'><div class=\"av-section-color-overlay-wrap\"><div class=\"av-section-color-overlay\"><\/div><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-1062'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-a7f91b8d75e9cc0c56b7d5f5b3aaf448\">\n#top .av-special-heading.av-av_heading-a7f91b8d75e9cc0c56b7d5f5b3aaf448{\npadding-bottom:20px;\nfont-size:50px;\n}\nbody .av-special-heading.av-av_heading-a7f91b8d75e9cc0c56b7d5f5b3aaf448 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-av_heading-a7f91b8d75e9cc0c56b7d5f5b3aaf448 .av-special-heading-tag{\nfont-size:50px;\n}\n.av-special-heading.av-av_heading-a7f91b8d75e9cc0c56b7d5f5b3aaf448 .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-av_heading-a7f91b8d75e9cc0c56b7d5f5b3aaf448 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-av_heading-a7f91b8d75e9cc0c56b7d5f5b3aaf448 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-a7f91b8d75e9cc0c56b7d5f5b3aaf448 av-special-heading-h1 blockquote modern-quote modern-centered  avia-builder-el-9  el_before_av_one_fifth  avia-builder-el-first  av-thin-font av-inherit-size'><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >ECHTE TECHNOLOGISCHE INNOVATIE<strong>.<\/strong><\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fifth-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_fifth-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fifth-6126cab7d8fab8d08143dd2dacdf673c av_one_fifth  avia-builder-el-10  el_after_av_heading  el_before_av_three_fifth  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_three_fifth-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_three_fifth-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_three_fifth-0aa7055fe62c3622faec82866afbaeb2 av_three_fifth  avia-builder-el-11  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-av_textblock-2de302bf1aa3cf4c9157dbe6f50ac7eb '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p style=\"text-align: center;\">Uit onze passie voor uw sport en technologische innovatie hebben we <strong>EYE-TRACK<\/strong> gecre\u00eberd: een elektronisch bewakingssysteem voor motorcrossbanen (en elk ander type baan), die gevaarlijke situaties aangeeft, net als een marshal, maar zonder enige beperking in tijd, aandacht of kosten.<\/p>\n<\/div><\/section><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2 av_one_fifth  avia-builder-el-13  el_after_av_three_fifth  el_before_av_button  flex_column_div av-zero-column-padding  '     ><\/div><div  class='avia-button-wrap av-av_button-4e12b2bdb48c4727656167fa8b4b4141-wrap avia-button-center  avia-builder-el-14  el_after_av_one_fifth  avia-builder-el-last '><a href=''  class='avia-button av-av_button-4e12b2bdb48c4727656167fa8b4b4141 av-link-btn avia-icon_select-yes-right-icon avia-size-large avia-position-center av-icon-on-hover avia-color-theme-color'   aria-label=\"ONTDEK EYE-TRACK\"><span class='avia_iconbox_title' >ONTDEK EYE-TRACK<\/span><span class='avia_button_icon avia_button_icon_right' aria-hidden='true' data-av_icon='\ue879' data-av_iconfont='entypo-fontello'><\/span><\/a><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><\/div><div id='av_section_2'  class='avia-section av-av_section-f1b7276c5e7cf3f8a111bb2d5c9bd7bf main_color avia-section-huge avia-no-border-styling  avia-builder-el-15  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-1062'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-7c100816f5d4231afb43e2b9ab114d96\">\n#top .av-special-heading.av-av_heading-7c100816f5d4231afb43e2b9ab114d96{\npadding-bottom:20px;\nfont-size:50px;\n}\nbody .av-special-heading.av-av_heading-7c100816f5d4231afb43e2b9ab114d96 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-av_heading-7c100816f5d4231afb43e2b9ab114d96 .av-special-heading-tag{\nfont-size:50px;\n}\n.av-special-heading.av-av_heading-7c100816f5d4231afb43e2b9ab114d96 .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-av_heading-7c100816f5d4231afb43e2b9ab114d96 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-av_heading-7c100816f5d4231afb43e2b9ab114d96 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-7c100816f5d4231afb43e2b9ab114d96 av-special-heading-h1 blockquote modern-quote modern-centered  avia-builder-el-16  el_before_av_one_fifth  avia-builder-el-first  av-inherit-size'><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >EYE-TRACK VERMINDERT HET RISICO<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fifth-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_fifth-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fifth-6126cab7d8fab8d08143dd2dacdf673c av_one_fifth  avia-builder-el-17  el_after_av_heading  el_before_av_three_fifth  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_three_fifth-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_three_fifth-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_three_fifth-0aa7055fe62c3622faec82866afbaeb2 av_three_fifth  avia-builder-el-18  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-av_textblock-2de302bf1aa3cf4c9157dbe6f50ac7eb '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p style=\"text-align: center;\"><strong>EYE-TRACK<\/strong> is in Itali\u00eb gemaakt met expertise en hoogwaardige elektronica, preciezer dan een menselijke operator, onder alle omstandigheden: warmte, kou, zonlicht en duisternis. Daarnaast wordt EYE-TRACK nooit moe of afgeleid.<\/p>\n<p style=\"text-align: center;\">EYE-TRACK signalen zijn duidelijk en zichtbaar voor iedereen, van rijders en mensen langs het spoor tot naar de track manager, allemaal dankzij een surveillance tv-scherm.<\/p>\n<\/div><\/section><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2 av_one_fifth  avia-builder-el-20  el_after_av_three_fifth  el_before_av_heading  flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-4c6edc025b0869109ba8f359f78980fe\">\n#top .av-special-heading.av-av_heading-4c6edc025b0869109ba8f359f78980fe{\npadding-bottom:20px;\nfont-size:50px;\n}\nbody .av-special-heading.av-av_heading-4c6edc025b0869109ba8f359f78980fe .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-av_heading-4c6edc025b0869109ba8f359f78980fe .av-special-heading-tag{\nfont-size:50px;\n}\n.av-special-heading.av-av_heading-4c6edc025b0869109ba8f359f78980fe .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-av_heading-4c6edc025b0869109ba8f359f78980fe .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-av_heading-4c6edc025b0869109ba8f359f78980fe .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-4c6edc025b0869109ba8f359f78980fe av-special-heading-h1 blockquote modern-quote modern-centered  avia-builder-el-21  el_after_av_one_fifth  el_before_av_one_fifth  av-thin-font av-inherit-size'><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >EYE-TRACK ONDER DE LOEP<strong>.<\/strong><\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fifth-9497bbf8bff73ea4c6992cc17fa9ec36\">\n.flex_column.av-av_one_fifth-9497bbf8bff73ea4c6992cc17fa9ec36{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fifth-9497bbf8bff73ea4c6992cc17fa9ec36 av_one_fifth  avia-builder-el-22  el_after_av_heading  el_before_av_three_fifth  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_three_fifth-9c1d454dc06f7247226bc4e8f931daae\">\n.flex_column.av-av_three_fifth-9c1d454dc06f7247226bc4e8f931daae{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_three_fifth-9c1d454dc06f7247226bc4e8f931daae av_three_fifth  avia-builder-el-23  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  '     ><div  class='avia-button-wrap av-av_button-4e12b2bdb48c4727656167fa8b4b4141-wrap avia-button-center  avia-builder-el-24  avia-builder-el-no-sibling '><a href=''  class='avia-button av-av_button-4e12b2bdb48c4727656167fa8b4b4141 av-link-btn avia-icon_select-yes-right-icon avia-size-large avia-position-center av-icon-on-hover avia-color-theme-color'   aria-label=\"ONTDEK EYE-TRACK\"><span class='avia_iconbox_title' >ONTDEK EYE-TRACK<\/span><span class='avia_button_icon avia_button_icon_right' aria-hidden='true' data-av_icon='\ue879' data-av_iconfont='entypo-fontello'><\/span><\/a><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fifth-9c1d454dc06f7247226bc4e8f931daae\">\n.flex_column.av-av_one_fifth-9c1d454dc06f7247226bc4e8f931daae{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fifth-9c1d454dc06f7247226bc4e8f931daae av_one_fifth  avia-builder-el-25  el_after_av_three_fifth  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_section-0b80476c520b2d8319f8d5b03761b646\">\n.avia-section.av-av_section-0b80476c520b2d8319f8d5b03761b646 .av-section-color-overlay{\nopacity:0.8;\nbackground-color:#000000;\n}\n<\/style>\n<div id='av_section_3'  class='avia-section av-av_section-0b80476c520b2d8319f8d5b03761b646 alternate_color avia-section-huge avia-no-border-styling  avia-builder-el-26  el_after_av_section  avia-builder-el-last  avia-bg-style-fixed av-section-color-overlay-active av-section-with-video-bg av-section-mobile-video-disabled container_wrap sidebar_right'   data-section-video-ratio='16:9'><div  class='avia-slideshow av_slideshow_obj-1-6a04570a57d85 avia-slideshow-featured av_slideshow avia-slide-slider av-slideshow-ui av-control-default av-slideshow-manual av-loop-once av-loop-manual-endless av-default-height-applied  av-section-video-bg avia-slideshow-2' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 28.666666666667%;'><li  data-controls='disabled' data-mute='aviaTBaviaTBvideo_mute' data-loop='1' data-disable-autoplay=''  data-video-ratio='1.7777777777778' class='avia-slideshow-slide av_slideshow_obj-1-6a04570a57d85__0  av-video-slide  av-video-service-youtube  av-hide-video-controls av-mute-video av-loop-video  av-single-slide slide-1 slide-odd'><div data-rel='slideshow-2' class='avia-slide-wrap '   ><div class='av-click-overlay'><\/div><div class='mejs-mediaelement'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\" ><div height='1600' width='900' class='av_youtube_frame' id='player_1062_421929969_958305086'  data-autoplay='0'  data-videoid='lOgZp_IrHgs'  data-hd='1'  data-rel='0'  data-wmode='opaque'  data-loop='0'  data-version='3'  data-autohide='1'  data-color='white'  data-controls='0'  data-iv_load_policy='3'  data-original_url='https:\/\/www.youtube.com\/watch?v=lOgZp_IrHgs' ><\/div><\/div><div class=\"av-click-to-play-overlay\"><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/li><\/ul><\/div><div class=\"av-section-color-overlay-wrap\"><div class=\"av-section-color-overlay\"><\/div><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-1062'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-ce3cf9c01de3222afd25cea1d83480cc\">\n#top .av-special-heading.av-av_heading-ce3cf9c01de3222afd25cea1d83480cc{\npadding-bottom:20px;\nfont-size:50px;\n}\nbody .av-special-heading.av-av_heading-ce3cf9c01de3222afd25cea1d83480cc .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-av_heading-ce3cf9c01de3222afd25cea1d83480cc .av-special-heading-tag{\nfont-size:50px;\n}\n.av-special-heading.av-av_heading-ce3cf9c01de3222afd25cea1d83480cc .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-av_heading-ce3cf9c01de3222afd25cea1d83480cc .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-av_heading-ce3cf9c01de3222afd25cea1d83480cc .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-ce3cf9c01de3222afd25cea1d83480cc av-special-heading-h1 blockquote modern-quote modern-centered  avia-builder-el-27  el_before_av_one_fifth  avia-builder-el-first  av-thin-font av-inherit-size'><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >WAAR WACHT JE OP<strong>?<\/strong><\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fifth-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_fifth-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fifth-6126cab7d8fab8d08143dd2dacdf673c av_one_fifth  avia-builder-el-28  el_after_av_heading  el_before_av_three_fifth  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_three_fifth-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_three_fifth-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_three_fifth-0aa7055fe62c3622faec82866afbaeb2 av_three_fifth  avia-builder-el-29  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  '     ><section  class='av_textblock_section av-av_textblock-2de302bf1aa3cf4c9157dbe6f50ac7eb '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p style=\"text-align: center;\">Onze ingenieurs hebben EYE-TRACK zo goed ontworpen dat het zo nauwkeurig is als de beste menselijke operator maar veel goedkoper en bovendien altijd beschikbaar.<\/p>\n<\/div><\/section><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2 av_one_fifth  avia-builder-el-31  el_after_av_three_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fifth-6126cab7d8fab8d08143dd2dacdf673c\">\n.flex_column.av-av_one_fifth-6126cab7d8fab8d08143dd2dacdf673c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fifth-6126cab7d8fab8d08143dd2dacdf673c av_one_fifth  avia-builder-el-32  el_after_av_one_fifth  el_before_av_one_fifth  first flex_column_div av-zero-column-padding  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_font_icon-bc55db16e7fccbec21d800ae767b26e0\">\n.av_font_icon.av-av_font_icon-bc55db16e7fccbec21d800ae767b26e0 .av-icon-char{\nfont-size:40px;\nline-height:40px;\nwidth:40px;\n}\n<\/style>\n<span  class='av_font_icon av-av_font_icon-bc55db16e7fccbec21d800ae767b26e0 avia_animate_when_visible av-icon-style-border avia-icon-pos-center av-no-color avia-icon-animate'><span class='av-icon-char' aria-hidden='true' data-av_icon='\ue8a2' data-av_iconfont='entypo-fontello' ><\/span><span class='av_icon_caption av-special-font'>Ultra <strong style=\"color: #f7ce46;\">BESTAND<\/strong><\/span><\/span><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2 av_one_fifth  avia-builder-el-34  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_font_icon-d5d13c0164038b0f0c89eb71b1582177\">\n.av_font_icon.av-av_font_icon-d5d13c0164038b0f0c89eb71b1582177 .av-icon-char{\nfont-size:40px;\nline-height:40px;\nwidth:40px;\n}\n<\/style>\n<span  class='av_font_icon av-av_font_icon-d5d13c0164038b0f0c89eb71b1582177 avia_animate_when_visible av-icon-style-border avia-icon-pos-center av-no-color avia-icon-animate'><span class='av-icon-char' aria-hidden='true' data-av_icon='\ue82b' data-av_iconfont='entypo-fontello' ><\/span><span class='av_icon_caption av-special-font'>MAKKELIJK TE <strong style=\"color: #f7ce46;\">INSTALLEREN<\/strong><\/span><\/span><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2 av_one_fifth  avia-builder-el-36  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_font_icon-da4597659eb2c651c7e3710841353d58\">\n.av_font_icon.av-av_font_icon-da4597659eb2c651c7e3710841353d58 .av-icon-char{\nfont-size:40px;\nline-height:40px;\nwidth:40px;\n}\n<\/style>\n<span  class='av_font_icon av-av_font_icon-da4597659eb2c651c7e3710841353d58 avia_animate_when_visible av-icon-style-border avia-icon-pos-center av-no-color avia-icon-animate'><span class='av-icon-char' aria-hidden='true' data-av_icon='\ue8aa' data-av_iconfont='entypo-fontello' ><\/span><span class='av_icon_caption av-special-font'>ALTIJD <strong style=\"color: #f7ce46;\">BESCHIKBAAR<\/strong><\/span><\/span><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2 av_one_fifth  avia-builder-el-38  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_font_icon-87d7baeb18474ede04a811bdbca2bb6f\">\n.av_font_icon.av-av_font_icon-87d7baeb18474ede04a811bdbca2bb6f .av-icon-char{\nfont-size:40px;\nline-height:40px;\nwidth:40px;\n}\n<\/style>\n<span  class='av_font_icon av-av_font_icon-87d7baeb18474ede04a811bdbca2bb6f avia_animate_when_visible av-icon-style-border avia-icon-pos-center av-no-color avia-icon-animate'><span class='av-icon-char' aria-hidden='true' data-av_icon='\ue8a8' data-av_iconfont='entypo-fontello' ><\/span><span class='av_icon_caption av-special-font'>VERPLICHTE<strong style=\"color: #f7ce46;\"> TIJDENS TRAININGSESSIES<\/strong><\/span><\/span><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2\">\n.flex_column.av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fifth-0aa7055fe62c3622faec82866afbaeb2 av_one_fifth  avia-builder-el-40  el_after_av_one_fifth  avia-builder-el-last  flex_column_div av-zero-column-padding  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_font_icon-9db841033eabcf23b48172fd957a4d96\">\n.av_font_icon.av-av_font_icon-9db841033eabcf23b48172fd957a4d96 .av-icon-char{\nfont-size:40px;\nline-height:40px;\nwidth:40px;\n}\n<\/style>\n<span  class='av_font_icon av-av_font_icon-9db841033eabcf23b48172fd957a4d96 avia_animate_when_visible av-icon-style-border avia-icon-pos-center av-no-color avia-icon-animate'><span class='av-icon-char' aria-hidden='true' data-av_icon='\ue840' data-av_iconfont='entypo-fontello' ><\/span><span class='av_icon_caption av-special-font'>DUIDELIJKE<strong style=\"color: #f7ce46;\"> SIGNALEN<\/strong><\/span><\/span><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><\/div><div id='after_section_3'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-1062'><div class='entry-content-wrapper clearfix'>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":13,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1062","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EYE-TRACK: een onzichtbaar elektronisch controlesysteem<\/title>\n<meta name=\"description\" content=\"EYE-TRACK het is een onzichtbaar elektronisch controlesysteem voor motorcross-tracks. EYE-TRACK kan op alle banen worden ge\u00efnstalleerd.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eye-track-sport.com\/nl\/welcome\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EYE-TRACK: een onzichtbaar elektronisch controlesysteem\" \/>\n<meta property=\"og:description\" content=\"EYE-TRACK het is een onzichtbaar elektronisch controlesysteem voor motorcross-tracks. EYE-TRACK kan op alle banen worden ge\u00efnstalleerd.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eye-track-sport.com\/nl\/welcome\/\" \/>\n<meta property=\"og:site_name\" content=\"EYE-TRACK\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-10T09:54:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eye-track-sport.com\/nl\/welcome\/\",\"url\":\"https:\/\/eye-track-sport.com\/nl\/welcome\/\",\"name\":\"EYE-TRACK: een onzichtbaar elektronisch controlesysteem\",\"isPartOf\":{\"@id\":\"https:\/\/eye-track-sport.com\/en\/#website\"},\"datePublished\":\"2017-11-03T09:54:52+00:00\",\"dateModified\":\"2024-07-10T09:54:33+00:00\",\"description\":\"EYE-TRACK het is een onzichtbaar elektronisch controlesysteem voor motorcross-tracks. EYE-TRACK kan op alle banen worden ge\u00efnstalleerd.\",\"breadcrumb\":{\"@id\":\"https:\/\/eye-track-sport.com\/nl\/welcome\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eye-track-sport.com\/nl\/welcome\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eye-track-sport.com\/nl\/welcome\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/eye-track-sport.com\/nl\/welcome\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Welcome\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eye-track-sport.com\/en\/#website\",\"url\":\"https:\/\/eye-track-sport.com\/en\/\",\"name\":\"EYE-TRACK\",\"description\":\"artificial intelligence for safety in sport facilities and public areas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eye-track-sport.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EYE-TRACK: een onzichtbaar elektronisch controlesysteem","description":"EYE-TRACK het is een onzichtbaar elektronisch controlesysteem voor motorcross-tracks. EYE-TRACK kan op alle banen worden ge\u00efnstalleerd.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eye-track-sport.com\/nl\/welcome\/","og_locale":"nl_NL","og_type":"article","og_title":"EYE-TRACK: een onzichtbaar elektronisch controlesysteem","og_description":"EYE-TRACK het is een onzichtbaar elektronisch controlesysteem voor motorcross-tracks. EYE-TRACK kan op alle banen worden ge\u00efnstalleerd.","og_url":"https:\/\/eye-track-sport.com\/nl\/welcome\/","og_site_name":"EYE-TRACK","article_modified_time":"2024-07-10T09:54:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"2 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eye-track-sport.com\/nl\/welcome\/","url":"https:\/\/eye-track-sport.com\/nl\/welcome\/","name":"EYE-TRACK: een onzichtbaar elektronisch controlesysteem","isPartOf":{"@id":"https:\/\/eye-track-sport.com\/en\/#website"},"datePublished":"2017-11-03T09:54:52+00:00","dateModified":"2024-07-10T09:54:33+00:00","description":"EYE-TRACK het is een onzichtbaar elektronisch controlesysteem voor motorcross-tracks. EYE-TRACK kan op alle banen worden ge\u00efnstalleerd.","breadcrumb":{"@id":"https:\/\/eye-track-sport.com\/nl\/welcome\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eye-track-sport.com\/nl\/welcome\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eye-track-sport.com\/nl\/welcome\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eye-track-sport.com\/nl\/welcome\/"},{"@type":"ListItem","position":2,"name":"Welcome"}]},{"@type":"WebSite","@id":"https:\/\/eye-track-sport.com\/en\/#website","url":"https:\/\/eye-track-sport.com\/en\/","name":"EYE-TRACK","description":"artificial intelligence for safety in sport facilities and public areas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eye-track-sport.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/eye-track-sport.com\/nl\/wp-json\/wp\/v2\/pages\/1062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eye-track-sport.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eye-track-sport.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eye-track-sport.com\/nl\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/eye-track-sport.com\/nl\/wp-json\/wp\/v2\/comments?post=1062"}],"version-history":[{"count":13,"href":"https:\/\/eye-track-sport.com\/nl\/wp-json\/wp\/v2\/pages\/1062\/revisions"}],"predecessor-version":[{"id":4282,"href":"https:\/\/eye-track-sport.com\/nl\/wp-json\/wp\/v2\/pages\/1062\/revisions\/4282"}],"wp:attachment":[{"href":"https:\/\/eye-track-sport.com\/nl\/wp-json\/wp\/v2\/media?parent=1062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}